{"id":5502,"date":"2025-12-08T02:55:59","date_gmt":"2025-12-08T02:55:59","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=5502"},"modified":"2025-12-08T02:55:59","modified_gmt":"2025-12-08T02:55:59","slug":"bl08-bubble-level","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/th\/product\/bl08-bubble-level\/","title":{"rendered":"\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33 BL08"},"content":{"rendered":"<p>\u0e40\u0e14\u0e2d\u0e30 <a href=\"https:\/\/mountlaser.com\/th\/\"><strong>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33 BL08<\/strong><\/a> \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e31\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a TRI Dini03 \u0e02\u0e2d\u0e07\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e35\u0e14\u0e33\u0e17\u0e19\u0e17\u0e32\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e2a\u0e14\u0e43\u0e2a\u0e15\u0e23\u0e07\u0e01\u0e25\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e31\u0e28\u0e19\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e43\u0e19\u0e17\u0e38\u0e01\u0e2a\u0e20\u0e32\u0e1e\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e31\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c BL08 \u0e21\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e19\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e02\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e22\u0e36\u0e14.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-5503\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1.webp\" alt=\"BL08 Bubble Level\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-12x12.webp 12w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/12\/BL081-1-400x400.webp 400w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e07 BL08 \u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e39\u0e07\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 <a href=\"https:\/\/mountlaser.com\/th\/product-category\/surveying-accessory\/\"><strong>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 TRI<\/strong><\/a>, \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e1a\u0e1a Total Station \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e17\u0e32\u0e07\u0e41\u0e2a\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e19\u0e17\u0e32\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e23\u0e07\u0e01\u0e25\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 TRI \u0e19\u0e35\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e19\u0e27\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22<a href=\"https:\/\/mountlaser.com\/th\/contact-us\/\"> \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 TRI<\/a> \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21.<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19: \u0e27\u0e07\u0e01\u0e25\u0e21\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e15\u0e23\u0e07\u0e01\u0e25\u0e32\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e41\u0e21\u0e49\u0e43\u0e19\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e08\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e2a\u0e07\u0e19\u0e49\u0e2d\u0e22.<\/li>\n<li>\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e19\u0e17\u0e32\u0e19: \u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e2a\u0e35\u0e14\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27.<\/li>\n<li>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33: \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e19\u0e27\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49.<\/li>\n<li>\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e23\u0e07\u0e01\u0e25\u0e21: \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a.<\/li>\n<\/ul>","protected":false},"featured_media":5504,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[79,153],"product_tag":[],"class_list":{"0":"post-5502","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-surveying-accessory","7":"product_cat-bubble-for-tribrach-carrier-prism","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product\/5502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/comments?post=5502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media\/5504"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media?parent=5502"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_brand?post=5502"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_cat?post=5502"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_tag?post=5502"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}