{"id":4777,"date":"2025-11-21T08:45:59","date_gmt":"2025-11-21T08:45:59","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=4777"},"modified":"2025-11-25T08:14:47","modified_gmt":"2025-11-25T08:14:47","slug":"rotary-laser-krl-420","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/th\/product\/rotary-laser-krl-420\/","title":{"rendered":"\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19 KRL-420"},"content":{"rendered":"<p>\u0e40\u0e14\u0e2d\u0e30 <a href=\"https:\/\/mountlaser.com\/th\/product-category\/rotary-laser\/]\/\"><strong>\u0e10\u0e32\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c KRL-420<\/strong><\/a> \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e17\u0e35\u0e48\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\/\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e42\u0e14\u0e22\u0e09\u0e32\u0e22\u0e23\u0e30\u0e19\u0e32\u0e1a 360 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e2a\u0e32\u0e19\u0e23\u0e27\u0e21\u0e44\u0e08\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e41\u0e25\u0e30\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e17\u0e36\u0e48\u0e07\u0e16\u0e36\u0e07 \u00b10.5 \u0e21\u0e21.\/10 \u0e21. \u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34.<\/p>\n<p>\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19 KRL-420 \u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e39\u0e07 (KRL-420R) \u0e41\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e1e\u0e34\u0e40\u0e28\u0e29 (KRL-420G)<a href=\"https:\/\/mountlaser.com\/th\/about-us\/\"><strong> \u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\/\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07<\/strong> <\/a>\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e22\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 1,000 \u0e40\u0e21\u0e15\u0e23 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a \u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e04\u0e23\u0e1a\u0e16\u0e49\u0e27\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 \u00b110% \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e14\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 RC100 \u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07 150 \u0e40\u0e21\u0e15\u0e23. <a href=\"https:\/\/mountlaser.com\/th\/\">\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\/\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07<\/a> \u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e19\u0e35\u0e49 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e19\u0e17\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 IP65 \u0e08\u0e36\u0e07\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e17\u0e19\u0e17\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e2a\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e32\u0e01\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4780\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203.webp\" alt=\"Horizontal\/Vertical Rotary Laser\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/KRL-4203-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19 KRL-420<\/strong><\/p>\n<table style=\"height: 683px;\" width=\"1045\">\n<tbody>\n<tr>\n<td>\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e0a\u0e19\u0e34\u0e14<\/td>\n<td>\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e25-420\u0e2d\u0e32\u0e23\u0e4c<\/td>\n<td>\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e25-420\u0e08\u0e35<\/td>\n<\/tr>\n<tr>\n<td>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\/\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e04\u0e25\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c<\/td>\n<td>\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e35\u0e41\u0e14\u0e07 (635nm-30mw) \u0e08\u0e38\u0e14\u0e1a\u0e19<\/td>\n<td>\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 (515nm-30mw) \u0e08\u0e38\u0e14\u0e1a\u0e19<\/td>\n<\/tr>\n<tr>\n<td>\u0e17\u0e32\u0e07\u0e23\u0e32\u0e1a<\/td>\n<td colspan=\"2\">\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (\u0e44\u0e08\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b 1 \u0e15\u0e31\u0e27 + \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e41\u0e01\u0e19 1 \u0e15\u0e31\u0e27)<\/td>\n<\/tr>\n<tr>\n<td>\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a<\/td>\n<td colspan=\"2\">\u00b15\u00b0<\/td>\n<\/tr>\n<tr>\n<td>\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a<\/td>\n<td colspan=\"2\">\u00b10.5 \u0e21\u0e21.\/10 \u0e21.<\/td>\n<\/tr>\n<tr>\n<td>\u0e44\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (\u0e43\u0e0a\u0e49 LP500)<\/td>\n<td colspan=\"2\">\u22651000\u0e21.<\/td>\n<\/tr>\n<tr>\n<td>\u0e44\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (\u0e43\u0e0a\u0e49 LP700)<\/td>\n<td colspan=\"2\">\u2265800\u0e21.<\/td>\n<\/tr>\n<tr>\n<td>\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/td>\n<td colspan=\"2\">-20\u2103 \u0e16\u0e36\u0e07 +50\u2103<\/td>\n<\/tr>\n<tr>\n<td>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c<\/td>\n<td colspan=\"2\">0\/300\/600\/1000\/1500 \u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35 (\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e49\u0e41\u0e1b\u0e23\u0e07\u0e16\u0e48\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e27\u0e07 \u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23)<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e2a\u0e41\u0e01\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48<\/td>\n<td colspan=\"2\">15\u00b0\/45\u00b0\/90\u00b0\/180\u00b0<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e35\u0e22\u0e07<\/td>\n<td colspan=\"2\">\u0e2a\u0e2d\u0e07\u0e17\u0e32\u0e07<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e19\u0e17\u0e32\u0e07\u0e25\u0e32\u0e14<\/td>\n<td colspan=\"2\">\u0e43\u0e0a\u0e49\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 RC100<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01<\/td>\n<td colspan=\"2\">12 \u0e1b\u0e38\u0e48\u0e21 \/ 5 \u0e44\u0e1f\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e30 (\u0e0b\u0e34\u0e07\u0e04\u0e4c\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25)<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25<\/td>\n<td colspan=\"2\">12 \u0e1b\u0e38\u0e48\u0e21 \/ 5 \u0e44\u0e1f\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e30 (\u0e0b\u0e34\u0e07\u0e42\u0e04\u0e23\u0e44\u0e19\u0e0b\u0e4c\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e01 \u0e23\u0e30\u0e22\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25 \u2265150 \u0e40\u0e21\u0e15\u0e23)<\/td>\n<\/tr>\n<tr>\n<td>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f<\/td>\n<td colspan=\"2\">\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21 (\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19) \u0e15\u0e48\u0e2d\u0e44\u0e1f AC \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/td>\n<\/tr>\n<tr>\n<td>\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21<\/td>\n<td colspan=\"2\">15-20 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 (\u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49)<\/td>\n<\/tr>\n<tr>\n<td>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a<\/td>\n<td colspan=\"2\">\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \/ \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/td>\n<\/tr>\n<tr>\n<td>\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<\/td>\n<td colspan=\"2\">\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01<\/td>\n<\/tr>\n<tr>\n<td>\u0e02\u0e19\u0e32\u0e14<\/td>\n<td colspan=\"2\">\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27 201 \u0e04\u0e27\u0e32\u0e21\u0e01\u0e27\u0e49\u0e32\u0e07 215 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07 232 (\u0e21\u0e21.)<\/td>\n<\/tr>\n<tr>\n<td>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19<\/td>\n<td colspan=\"2\">IP65<\/td>\n<\/tr>\n<tr>\n<td>\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01<\/td>\n<td colspan=\"2\">1M \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/td>\n<\/tr>\n<tr>\n<td>\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19<\/td>\n<td colspan=\"2\">\u00b110%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<ul>\n<li>\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e23\u0e30\u0e19\u0e32\u0e1a: \u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\/\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e43\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e23\u0e30\u0e19\u0e32\u0e1a.<\/li>\n<li>\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07: \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e08\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e41\u0e25\u0e30\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u00b10.5 \u0e21\u0e21.\/10 \u0e21. \u0e20\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 \u00b15\u00b0.<\/li>\n<li>\u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25: \u0e23\u0e35\u0e42\u0e21\u0e17 RC100 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19 \u0e08\u0e32\u0e01\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e16\u0e36\u0e07 150 \u0e40\u0e21\u0e15\u0e23.<\/li>\n<\/ul>","protected":false},"featured_media":4779,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[93,137],"product_tag":[],"class_list":{"0":"post-4777","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rotary-laser","7":"product_cat-rotary-laser-4-series","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product\/4777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/comments?post=4777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media\/4779"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media?parent=4777"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_brand?post=4777"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_cat?post=4777"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_tag?post=4777"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}