{"id":4649,"date":"2025-11-20T07:14:18","date_gmt":"2025-11-20T07:14:18","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=4649"},"modified":"2025-11-26T06:56:10","modified_gmt":"2025-11-26T06:56:10","slug":"rltb01-rotary-laser-tilting-base","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/th\/product\/rltb01-rotary-laser-tilting-base\/","title":{"rendered":"\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19 RLTB01"},"content":{"rendered":"<p>\u0e40\u0e14\u0e2d\u0e30 <a href=\"https:\/\/mountlaser.com\/th\/\"><strong>\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19 RLTB01<\/strong><\/a> \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e21\u0e38\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d \u0e10\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e23\u0e38\u0e48\u0e19 RLTB01 \u0e19\u0e35\u0e49 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e01\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e44\u0e14\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e19\u0e27 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07.<\/p>\n<p>\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 <a href=\"https:\/\/mountlaser.com\/th\/products\/\"><strong>\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c<\/strong><\/a>, \u0e40\u0e23\u0e32\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32\u0e10\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e44\u0e14\u0e49\u0e23\u0e38\u0e48\u0e19 RLTB01 \u0e21\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e10\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e19\u0e17\u0e32\u0e19\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e0a\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4650\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011.webp\" alt=\"RLTB01 Rotary Laser Tilting Base\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/RLTB011-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22 <a href=\"https:\/\/mountlaser.com\/th\/about-us\/\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/a> \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e38\u0e48\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01.<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2b\u0e21\u0e38\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e32\u0e14\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e41\u0e01\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27<\/li>\n<li>\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e35\u0e22\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e21\u0e38\u0e21\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e31\u0e19<\/li>\n<li>\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e17\u0e19\u0e17\u0e32\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/li>\n<li>\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c<\/li>\n<\/ul>","protected":false},"featured_media":4654,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[94,133],"product_tag":[],"class_list":{"0":"post-4649","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-laser-level-accessory","7":"product_cat-rotary-laser-tilting-base","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product\/4649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/comments?post=4649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media\/4654"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media?parent=4649"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_brand?post=4649"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_cat?post=4649"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_tag?post=4649"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}