{"id":2906,"date":"2025-10-24T08:07:11","date_gmt":"2025-10-24T08:07:11","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=2906"},"modified":"2025-11-28T05:19:19","modified_gmt":"2025-11-28T05:19:19","slug":"qpps-aluminum-pole-tripod","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/th\/product\/qpps-aluminum-pole-tripod\/","title":{"rendered":"\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 QPPS"},"content":{"rendered":"<p>\u0e40\u0e14\u0e2d\u0e30 <a href=\"https:\/\/mountlaser.com\/th\/\"><strong>\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 QPPS<\/strong><\/a> \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e41\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e02\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e35\u0e1a\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e44\u0e01\u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e04\u0e40\u0e23\u0e47\u0e27\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e32 \u0e40\u0e2a\u0e32\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e41\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e02\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e35\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49 \u0e21\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e17\u0e35\u0e48\u0e25\u0e07\u0e15\u0e31\u0e27\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e2a\u0e19\u0e32\u0e21\u0e17\u0e35\u0e48\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2909\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5.webp\" alt=\"Aluminum Pole Tripod with Clamp\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/QPPS-5-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e19\u0e35\u0e1a\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e32\u0e07\u0e41\u0e25\u0e30\u0e25\u0e47\u0e2d\u0e04\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e41\u0e1a\u0e1a\u0e01\u0e23\u0e23\u0e44\u0e01\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07... <a href=\"https:\/\/mountlaser.com\/th\/products\/\"><strong>\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e35\u0e1a<\/strong><\/a> \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e22\u0e30\u0e01\u0e32\u0e23\u0e22\u0e37\u0e14\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e16\u0e36\u0e07 120 \u0e0b\u0e21. \u0e08\u0e36\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e14\u0e49\u0e27\u0e22\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e02\u0e19\u0e32\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 18\/25 \u0e21\u0e21. \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e43\u0e2a\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e19\u0e38\u0e48\u0e21\u0e41\u0e25\u0e30\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e43\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a.<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>\u0e01\u0e25\u0e44\u0e01\u0e41\u0e04\u0e25\u0e21\u0e1b\u0e4c\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e14\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e47\u0e2d\u0e04\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/li>\n<li>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e32 \u0e40\u0e2a\u0e32\u0e1b\u0e23\u0e34\u0e0b\u0e36\u0e21 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e23\u0e30\u0e14\u0e31\u0e1a<\/li>\n<li>\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e39\u0e07<\/li>\n<li>\u0e23\u0e30\u0e22\u0e30\u0e22\u0e37\u0e14\u0e44\u0e14\u0e49 120 \u0e0b\u0e21. \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e25\u0e47\u0e2d\u0e01\u0e02\u0e32\u0e41\u0e1a\u0e1a\u0e22\u0e37\u0e14\u0e2b\u0e14\u0e44\u0e14\u0e49<\/li>\n<\/ul>","protected":false},"featured_media":2907,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[91,107],"product_tag":[],"class_list":{"0":"post-2906","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bipod-tripod","7":"product_cat-aluminum-pole-tripod","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product\/2906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/comments?post=2906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media\/2907"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/media?parent=2906"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_brand?post=2906"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_cat?post=2906"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/th\/wp-json\/wp\/v2\/product_tag?post=2906"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}