{"id":4153,"date":"2025-11-12T09:09:06","date_gmt":"2025-11-12T09:09:06","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=4153"},"modified":"2025-11-27T05:56:05","modified_gmt":"2025-11-27T05:56:05","slug":"dz520-aluminum-prism-pole","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/it\/prodotto\/dz520-aluminum-prism-pole\/","title":{"rendered":"Palo prismatico in alluminio DZ520"},"content":{"rendered":"<p>Noi di Mount Laser sappiamo che la precisione delle misurazioni della tua stazione totale dipende dall&#039;affidabilit\u00e0 di ogni componente del tuo kit di strumenti. Ecco perch\u00e9 abbiamo progettato <a href=\"https:\/\/mountlaser.com\/it\/\"><strong>Palo prismatico in alluminio DZ520<\/strong><\/a>, un&#039;asta prismatica di livello professionale per stazione totale che unisce leggerezza e durevolezza a funzionalit\u00e0 eccezionali.<\/p>\n<p>Realizzato interamente in alluminio ad alta resistenza, il palo prismatico in alluminio DZ520 \u00e8 progettato per resistere alle sollecitazioni dell&#039;uso quotidiano in qualsiasi cantiere, senza appesantire. Il suo robusto design a 4 sezioni si estende fino a un&#039;altezza massima di 5,2 m., <a href=\"https:\/\/mountlaser.com\/it\/products\/\"><strong>Palo prismatico per stazione totale<\/strong><\/a> offrendoti la portata di cui hai bisogno per diverse applicazioni di rilevamento.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4156\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2.webp\" alt=\"Prism pole for total station\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/DZ520QL2-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><a href=\"https:\/\/mountlaser.com\/it\/contact-us\/\">Palo prismatico in alluminio DZ520<\/a> OPZIONE DI BLOCCO: Disponibile in quattro tipi:<br \/>\nPalo prismatico in alluminio con blocco a torsione<br \/>\nPalo prismatico in alluminio con blocco a sgancio rapido<br \/>\nPalo prismatico in alluminio con blocco stile GPS<\/p>\n<p><strong>Specifiche del palo prismatico in alluminio DZ520<\/strong><\/p>\n<table style=\"border-collapse: collapse; width: 741.77pt;\" border=\"0\" width=\"989\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 142.50pt;\" width=\"190\" height=\"19\">NUMERO<\/td>\n<td class=\"et2\" style=\"width: 127.50pt;\" width=\"170\">LUNGHEZZA<\/td>\n<td class=\"et2\" style=\"width: 126.00pt;\" width=\"168\">MATERIALE<\/td>\n<td class=\"et2\" style=\"width: 135.00pt;\" width=\"180\">LAUREATI<\/td>\n<td class=\"et2\" style=\"width: 124.50pt;\" width=\"166\">OPZIONE DI BLOCCO<\/td>\n<td class=\"et2\" style=\"width: 86.25pt;\" width=\"115\">DIAMETRO<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et3\" style=\"height: 14.25pt;\" height=\"19\">DZ520<\/td>\n<td class=\"et4\">520 centimetri<\/td>\n<td class=\"et3\">Alluminio<\/td>\n<td class=\"et3\">metro<\/td>\n<td class=\"et3\">TL\/ QL\/ GP<\/td>\n<td class=\"et3\">18\/25\/30\/36 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Bolla circolare integrata da 30&quot;: consente un livellamento rapido e semplice, fondamentale per ottenere misurazioni verticali precise con l&#039;asta prismatica per stazione totale.<\/li>\n<li>Scala graduata trasparente per misuratori di altezza: fornisce una rapida conferma visiva delle impostazioni di altezza, semplificando il flusso di lavoro e riducendo gli errori.<\/li>\n<li>Montaggio versatile del prisma: compatibile con diverse opzioni di adattatore, semplificando il collegamento del modello di prisma specifico.<\/li>\n<\/ul>","protected":false},"featured_media":4154,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[89,117],"product_tag":[],"class_list":{"0":"post-4153","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-surveying-pole-rod","7":"product_cat-aluminum-prism-pole","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product\/4153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/comments?post=4153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media\/4154"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media?parent=4153"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_brand?post=4153"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_cat?post=4153"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_tag?post=4153"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}