{"id":3218,"date":"2025-11-03T09:09:42","date_gmt":"2025-11-03T09:09:42","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=3218"},"modified":"2025-11-28T03:04:21","modified_gmt":"2025-11-28T03:04:21","slug":"premium-t-series-heavy-duty-aluminum-tripod","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/it\/prodotto\/premium-t-series-heavy-duty-aluminum-tripod\/","title":{"rendered":"Treppiede in alluminio per impieghi gravosi Premium serie T"},"content":{"rendered":"<p>Serie T Premium <a href=\"https:\/\/mountlaser.com\/it\/\"><strong>Treppiede in alluminio per impieghi gravosi STA30<\/strong><\/a>, un treppiede per topografia in alluminio ad alta resistenza di alta qualit\u00e0, progettato per garantire precisione e resistenza. Questo robusto treppiede per topografia in alluminio con gambe quadrate \u00e8 disponibile con tre tipi di testa: testa piatta, testa bombata e testa tonda grande, per adattarsi perfettamente al tuo strumento, rendendolo ideale per l&#039;uso con stazioni totali.<\/p>\n<p>Progettato con un design esclusivo del piede e una struttura a gambe quadrate, offre una stabilit\u00e0 superiore su qualsiasi terreno. Il nostro avanzato meccanismo di bloccaggio rapido riduce lo sforzo operativo e garantisce una maggiore durata. Realizzato in lega di alluminio ad alta resistenza, questo treppiede per rilievi topografici in alluminio per impieghi gravosi offre un&#039;eccellente resistenza agli urti.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3221\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2.webp\" alt=\"Square Leg Surveying Aluminum Tripod\" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/11\/STA30-DCD2-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><br \/>\n\u00c8 dotato di un meccanismo autobloccante standard per un facile trasporto e di un bullone a forcella in ottone da 5\/8\u2033-11 per una compatibilit\u00e0 universale. Come versatile <a href=\"https:\/\/mountlaser.com\/it\/about-us\/\"><strong>Treppiede in alluminio per rilievi topografici con gambe quadrate<\/strong><\/a>, offriamo anche colori e altezze personalizzati su richiesta per soddisfare le esigenze specifiche del tuo progetto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Specifiche del treppiede in alluminio per impieghi gravosi Premium T Series STA30<\/strong><\/p>\n<table style=\"border-collapse: collapse; width: 622.52pt;\" border=\"0\" width=\"830\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 94.50pt;\" width=\"126\" height=\"19\">NUMERO<\/td>\n<td class=\"et2\" style=\"width: 97.50pt;\" width=\"130\">GAMBE<\/td>\n<td class=\"et2\" style=\"width: 90.75pt;\" width=\"121\">TESTA<\/td>\n<td class=\"et2\" style=\"width: 100.50pt;\" width=\"134\">TIPO DI BLOCCO<\/td>\n<td class=\"et2\" style=\"width: 99.00pt;\" width=\"132\">HARDWARE<\/td>\n<td class=\"et2\" style=\"width: 86.25pt;\" width=\"115\">ESTENSIONE<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">Nord-Ovest<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt;\" height=\"19\">STA30-FCTSYL<\/td>\n<td class=\"et2\">Alluminio<\/td>\n<td class=\"et2\">160 mm piatto<\/td>\n<td class=\"et2\">Morsetto a torsione<\/td>\n<td class=\"et2\">Giallo<\/td>\n<td class=\"et2\">174 centimetri<\/td>\n<td class=\"et2\">4,5 kg<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt;\" height=\"19\">STA30-FCDSYL<\/td>\n<td class=\"et2\">Alluminio<\/td>\n<td class=\"et2\">160 mm piatto<\/td>\n<td class=\"et2\">Doppio morsetto<\/td>\n<td class=\"et2\">Giallo<\/td>\n<td class=\"et2\">168 centimetri<\/td>\n<td class=\"et2\">5,1 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Garantisce un&#039;installazione rapida e sicura e una regolazione dell&#039;altezza senza sforzo grazie al meccanismo di bloccaggio rapido avanzato.<\/li>\n<li>Resiste alle condizioni di lavoro pi\u00f9 difficili grazie alla sua robusta struttura in lega di alluminio.<\/li>\n<li>Offre un&#039;ampia compatibilit\u00e0 con gli strumenti con un bullone a forcella in ottone standard da 5\/8\u2033-11.<\/li>\n<\/ul>","protected":false},"featured_media":3219,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[91,111],"product_tag":[],"class_list":{"0":"post-3218","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bipod-tripod","7":"product_cat-aluminum-surveying-tripod","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product\/3218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/comments?post=3218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media\/3219"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media?parent=3218"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_brand?post=3218"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_cat?post=3218"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_tag?post=3218"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}