{"id":2591,"date":"2025-10-13T09:10:16","date_gmt":"2025-10-13T09:10:16","guid":{"rendered":"https:\/\/mountlaser.com\/?post_type=product&#038;p=2591"},"modified":"2025-11-28T07:01:27","modified_gmt":"2025-11-28T07:01:27","slug":"z15u-prism-assembly","status":"publish","type":"product","link":"https:\/\/mountlaser.com\/it\/prodotto\/z15u-prism-assembly\/","title":{"rendered":"Gruppo prisma Z15U"},"content":{"rendered":"<p>Aumenta la precisione dei tuoi rilievi con <a href=\"https:\/\/mountlaser.com\/it\/\"><strong>Gruppo prisma Z15U<\/strong><\/a>, un vero sistema prismatico ad alta precisione, costruito secondo gli standard rigorosi di un supporto prismatico in stile giapponese. Questo sistema prismatico ad alta precisione \u00e8 progettato per i professionisti che non possono scendere a compromessi in termini di precisione, con un prisma da 64 mm con una precisione angolare a scelta di 3-4&quot; o 5-8&quot;. \u00c8 progettato per un utilizzo versatile sul campo, offrendo un offset di 0 mm o -30 mm e un&#039;altezza dell&#039;asse di inclinazione di 100 mm per un posizionamento ottimale.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2593\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2.webp\" alt=\"high-precision prism system \" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-YY-2-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>L&#039;assemblaggio garantisce una compatibilit\u00e0 universale grazie all&#039;adattatore integrato in alluminio con filettatura femmina da 5\/8\u2033-11, compatibile con tutti i pali e gli accessori standard. Per semplificare la gestione del progetto e l&#039;identificazione degli utensili, offriamo questo affidabile <a href=\"https:\/\/mountlaser.com\/it\/products\/\"><strong>sistema di prismi ad alta precisione<\/strong><\/a> in due modelli distinti, codificati a colori: il gruppo prismatico Z15U-RO (rosso-arancione) e il <a href=\"https:\/\/mountlaser.com\/it\/contact-us\/\"><strong>Gruppo prisma Z15U-YY<\/strong><\/a> (Giallo). Sia il gruppo prisma Z15U-RO che il gruppo prisma Z15U-YY sono dotati di una custodia resistente per il trasporto, che garantisce la protezione del vostro investimento durante il trasporto e lo stoccaggio.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2597\" src=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4.webp\" alt=\"high-precision prism system \" width=\"500\" height=\"500\" srcset=\"https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4.webp 1000w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-300x300.webp 300w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-400x400.webp 400w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-800x800.webp 800w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-600x600.webp 600w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-150x150.webp 150w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-768x768.webp 768w, https:\/\/mountlaser.com\/wp-content\/uploads\/2025\/10\/Z15U-RO-4-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Impostazione configurabile: consente di scegliere tra un offset di 0 mm o -30 mm e un asse di inclinazione di 100 mm per configurazioni di campo flessibili.<\/li>\n<li>Compatibilit\u00e0 universale: l&#039;adattatore filettato femmina da 5\/8\u2033-11 integrato garantisce un utilizzo senza problemi con le apparecchiature di rilevamento standard.<\/li>\n<li>Identificazione tramite codice colore: disponibile nei colori Z15U-RO (rosso-arancione) e Z15U-YY (giallo) per una facile differenziazione tra team e progetti.<\/li>\n<\/ul>","protected":false},"featured_media":2593,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[72,103],"product_tag":[],"class_list":{"0":"post-2591","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-reflective-target-prism","7":"product_cat-prism-assembly","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product\/2591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/comments?post=2591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media\/2593"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/media?parent=2591"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_brand?post=2591"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_cat?post=2591"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mountlaser.com\/it\/wp-json\/wp\/v2\/product_tag?post=2591"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}