{"id":99,"count":5,"description":"Le tribrach de style japonais de Mount Laser repr\u00e9sente le summum de la conception pour les lev\u00e9s topographiques, alliant pr\u00e9cision et portabilit\u00e9 exceptionnelle. Ce tribrach innovant de style japonais se distingue par sa construction compacte et l\u00e9g\u00e8re, sans compromis sur la stabilit\u00e9 ni la pr\u00e9cision. Contrairement aux tribrachs traditionnels, ce mod\u00e8le avanc\u00e9 int\u00e8gre un m\u00e9canisme de d\u00e9gagement rapide unique permettant aux g\u00e9om\u00e8tres d&#039;installer et de repositionner leur \u00e9quipement en quelques secondes. Disponible avec des filetages 5\/8&quot;-11 ou 3\/8&quot;-16, ce tribrach polyvalent de style japonais assure une compatibilit\u00e9 parfaite avec divers instruments de topographie.","link":"https:\/\/mountlaser.com\/fr_fr\/categorie-produit\/surveying-accessory\/japanese-style-tribrach\/","name":"Tribrach de style japonais","slug":"japanese-style-tribrach","taxonomy":"product_cat","parent":79,"meta":[],"menu_order":19,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/79"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product?product_cat=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}