{"id":144,"count":5,"description":"La gamme de th\u00e9odolites, distribu\u00e9e par Mountlaser, est un instrument de mesure d&#039;angles de haute pr\u00e9cision con\u00e7u pour les professionnels de l&#039;ing\u00e9nierie et de la topographie. La fonction principale du th\u00e9odolite (vente par agent) est d&#039;effectuer des mesures d&#039;angles pr\u00e9cises dans les plans horizontal et vertical gr\u00e2ce \u00e0 une lunette et un cadran gradu\u00e9 avec pr\u00e9cision, ce qui en fait un outil indispensable pour tous les travaux de topographie.","link":"https:\/\/mountlaser.com\/fr_fr\/categorie-produit\/agent-sales\/theodoliteagent-sales\/","name":"Th\u00e9odolite (Vente par agent)","slug":"theodoliteagent-sales","taxonomy":"product_cat","parent":95,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/95"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product?product_cat=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}