{"id":105,"count":15,"description":"Les prismes \u00e0 cube d&#039;angle, souvent traduits par \" prisme \u00e0 cube d&#039;angle \" ou \" prisme conique \u00e0 angle droit \", sont un type particulier de prisme optique. Ils poss\u00e8dent trois surfaces r\u00e9fl\u00e9chissantes perpendiculaires et une surface d&#039;incidence triangulaire, dont la forme rappelle celle d&#039;un coin de cube.","link":"https:\/\/mountlaser.com\/fr_fr\/categorie-produit\/reflective-target-prism\/corner-cube-prisms\/","name":"Prismes cubiques d&#039;angle","slug":"corner-cube-prisms","taxonomy":"product_cat","parent":72,"meta":[],"menu_order":8,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/72"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product?product_cat=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}