{"id":101,"count":2,"description":"Le tribrach de pr\u00e9cision standard est un outil indispensable dans le monde de la topographie, offrant un \u00e9quilibre id\u00e9al entre robustesse, excellent rapport qualit\u00e9-prix et pr\u00e9cision fiable pour une large gamme d&#039;applications. Con\u00e7u pour un usage quotidien, il fournit une base stable et s\u00e9curis\u00e9e pour les stations totales et les niveaux optiques, garantissant des r\u00e9sultats constants sur les chantiers, lors de lev\u00e9s topographiques et pour les travaux d&#039;implantation courants. Ce tribrach b\u00e9n\u00e9ficie d&#039;une construction robuste avec des composants m\u00e9talliques pour une long\u00e9vit\u00e9 accrue et des m\u00e9canismes de serrage fiables. Pour les professionnels recherchant une solution \u00e9conomique sans compromis sur la pr\u00e9cision, le tribrach de pr\u00e9cision standard offre les performances fiables n\u00e9cessaires pour un travail efficace et pr\u00e9cis.","link":"https:\/\/mountlaser.com\/fr_fr\/categorie-produit\/surveying-accessory\/standard-precision-tribrach\/","name":"Tribrach de pr\u00e9cision standard","slug":"standard-precision-tribrach","taxonomy":"product_cat","parent":79,"meta":[],"menu_order":14,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product_cat\/79"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/product?product_cat=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}