{"id":1596,"date":"2024-12-06T08:59:37","date_gmt":"2024-12-06T08:59:37","guid":{"rendered":"https:\/\/startersites.io\/elementor\/pottery\/?page_id=3"},"modified":"2025-12-30T09:05:34","modified_gmt":"2025-12-30T09:05:34","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/mountlaser.com\/fr_fr\/privacy-policy\/","title":{"rendered":"politique de confidentialit\u00e9"},"content":{"rendered":"<h2 class=\"wp-block-heading\">politique de confidentialit\u00e9<\/h2>\n\n\n\n<p>Mount Laser exploite ce magasin et ce site web, y compris toutes les informations, contenus, fonctionnalit\u00e9s, outils, produits et services associ\u00e9s, afin de vous offrir, en tant que client, une exp\u00e9rience d&#039;achat personnalis\u00e9e (les \u201c Services \u201d).<\/p>\n\n\n\n<p>La pr\u00e9sente Politique de confidentialit\u00e9 d\u00e9crit comment nous recueillons, utilisons et divulguons vos renseignements personnels lorsque vous visitez nos Services, les utilisez, effectuez un achat ou toute autre transaction par leur interm\u00e9diaire ou communiquez avec nous. En cas de conflit entre nos Conditions d&#039;utilisation et la pr\u00e9sente Politique de confidentialit\u00e9, cette derni\u00e8re pr\u00e9vaut en ce qui concerne la collecte, le traitement et la divulgation de vos renseignements personnels.<\/p>\n\n\n\n<p>Veuillez lire attentivement la pr\u00e9sente Politique de confidentialit\u00e9. En utilisant nos Services, vous reconnaissez avoir pris connaissance de cette Politique de confidentialit\u00e9 et comprendre la collecte, l&#039;utilisation et la divulgation de vos informations telles que d\u00e9crites dans la pr\u00e9sente Politique de confidentialit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Informations personnelles que nous recueillons ou traitons<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Lorsque nous utilisons le terme \u201c\u00a0renseignements personnels\u00a0\u201d, nous faisons r\u00e9f\u00e9rence aux renseignements qui permettent de vous identifier ou qui peuvent raisonnablement \u00eatre associ\u00e9s \u00e0 vous ou \u00e0 une autre personne. Les renseignements personnels n\u2019incluent pas les renseignements recueillis de fa\u00e7on anonyme ou d\u00e9personnalis\u00e9s, de sorte qu\u2019ils ne permettent pas de vous identifier ou d\u2019\u00eatre raisonnablement associ\u00e9s \u00e0 vous. Nous pouvons recueillir ou traiter les cat\u00e9gories de renseignements personnels suivantes, y compris les d\u00e9ductions qui en d\u00e9coulent, selon votre utilisation des Services, votre lieu de r\u00e9sidence et conform\u00e9ment \u00e0 la loi applicable\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Coordonn\u00e9es<\/strong>&nbsp;y compris vos nom, adresse, adresse de facturation, adresse de livraison, num\u00e9ro de t\u00e9l\u00e9phone et adresse e-mail.<\/li>\n\n\n\n<li><strong>Informations financi\u00e8res<\/strong>&nbsp;y compris les num\u00e9ros de carte de cr\u00e9dit, de carte de d\u00e9bit et de compte financier, les informations relatives aux cartes de paiement, les informations relatives aux comptes financiers, les d\u00e9tails des transactions, le mode de paiement, la confirmation de paiement et autres d\u00e9tails de paiement.<\/li>\n\n\n\n<li><strong>Informations sur le compte<\/strong>&nbsp;y compris votre nom d&#039;utilisateur, votre mot de passe, vos questions de s\u00e9curit\u00e9, vos pr\u00e9f\u00e9rences et vos param\u00e8tres.<\/li>\n\n\n\n<li><strong>Informations sur la transaction<\/strong>&nbsp;y compris les articles que vous consultez, mettez dans votre panier, ajoutez \u00e0 votre liste de souhaits, ou achetez, retournez, \u00e9changez ou annulez, ainsi que vos transactions pass\u00e9es.<\/li>\n\n\n\n<li><strong>Communications avec nous<\/strong>&nbsp;y compris les informations que vous nous communiquez, par exemple lorsque vous nous envoyez une demande d&#039;assistance client.<\/li>\n\n\n\n<li><strong>Informations sur l&#039;appareil<\/strong>&nbsp;y compris des informations concernant votre appareil, votre navigateur ou votre connexion r\u00e9seau, votre adresse IP et d&#039;autres identifiants uniques.<\/li>\n\n\n\n<li><strong>Informations d&#039;utilisation<\/strong>&nbsp;y compris des informations concernant votre interaction avec les Services, notamment comment et quand vous interagissez avec les Services ou y naviguez.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sources d&#039;information personnelle<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Nous pouvons recueillir des renseignements personnels provenant des sources suivantes\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Directement de vous<\/strong>&nbsp;notamment lorsque vous cr\u00e9ez un compte, visitez ou utilisez les Services, communiquez avec nous ou nous fournissez autrement vos renseignements personnels;<\/li>\n\n\n\n<li><strong>Automatiquement par le biais des Services<\/strong>&nbsp;notamment depuis votre appareil lorsque vous utilisez nos produits ou services ou visitez nos sites Web, et gr\u00e2ce \u00e0 l\u2019utilisation de cookies et de technologies similaires\u00a0;<\/li>\n\n\n\n<li><strong>De nos prestataires de services<\/strong>&nbsp;y compris lorsque nous faisons appel \u00e0 eux pour mettre en \u0153uvre certaines technologies et lorsqu&#039;ils collectent ou traitent vos informations personnelles en notre nom\u00a0;<\/li>\n\n\n\n<li><strong>De nos partenaires ou d&#039;autres tiers.<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment nous utilisons vos informations personnelles<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Selon la mani\u00e8re dont vous interagissez avec nous ou les Services que vous utilisez, nous pouvons utiliser vos renseignements personnels aux fins suivantes\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fournir, adapter et am\u00e9liorer les services.<\/strong>&nbsp;Nous utilisons vos informations personnelles pour vous fournir les Services, notamment pour ex\u00e9cuter notre contrat avec vous, traiter vos paiements, honorer vos commandes, m\u00e9moriser vos pr\u00e9f\u00e9rences et les articles qui vous int\u00e9ressent, vous envoyer des notifications relatives \u00e0 votre compte, traiter les achats, les retours, les \u00e9changes et autres transactions, cr\u00e9er, g\u00e9rer et maintenir votre compte, organiser l&#039;exp\u00e9dition, faciliter les retours et les \u00e9changes, vous permettre de publier des avis et vous offrir une exp\u00e9rience d&#039;achat personnalis\u00e9e, par exemple en vous recommandant des produits similaires \u00e0 vos achats. Cela peut \u00e9galement inclure l&#039;utilisation de vos informations personnelles pour mieux adapter et am\u00e9liorer les Services.<\/li>\n\n\n\n<li><strong>Marketing et publicit\u00e9.<\/strong>&nbsp;Nous utilisons vos informations personnelles \u00e0 des fins de marketing et de promotion, notamment pour vous envoyer des communications marketing, publicitaires et promotionnelles par e-mail, SMS ou courrier postal, et pour vous pr\u00e9senter des publicit\u00e9s en ligne pour des produits ou services sur les Services ou d&#039;autres sites web, y compris en fonction des articles que vous avez pr\u00e9c\u00e9demment achet\u00e9s ou ajout\u00e9s \u00e0 votre panier et d&#039;autres activit\u00e9s sur les Services.<\/li>\n\n\n\n<li><strong>S\u00e9curit\u00e9 et pr\u00e9vention de la fraude.<\/strong>&nbsp;Nous utilisons vos informations personnelles pour authentifier votre compte, vous offrir une exp\u00e9rience de paiement et d&#039;achat s\u00e9curis\u00e9e, d\u00e9tecter, enqu\u00eater sur et prendre des mesures concernant d&#039;\u00e9ventuelles activit\u00e9s frauduleuses, ill\u00e9gales, dangereuses ou malveillantes, prot\u00e9ger la s\u00e9curit\u00e9 publique et s\u00e9curiser nos services. Si vous choisissez d&#039;utiliser nos services et de cr\u00e9er un compte, il vous incombe de prot\u00e9ger vos identifiants de connexion. Nous vous recommandons vivement de ne communiquer votre nom d&#039;utilisateur, votre mot de passe ni aucune autre information d&#039;acc\u00e8s \u00e0 qui que ce soit.<\/li>\n\n\n\n<li><strong>Communiquer avec vous.<\/strong>&nbsp;Nous utilisons vos informations personnelles pour vous fournir une assistance client\u00e8le, r\u00e9pondre \u00e0 vos demandes, vous offrir des services efficaces et maintenir notre relation commerciale avec vous.<\/li>\n\n\n\n<li><strong>Raisons juridiques.<\/strong>&nbsp;Nous utilisons vos informations personnelles pour nous conformer \u00e0 la loi applicable ou r\u00e9pondre \u00e0 une proc\u00e9dure judiciaire valide, y compris les demandes des forces de l&#039;ordre ou des agences gouvernementales, pour enqu\u00eater ou participer \u00e0 une proc\u00e9dure de d\u00e9couverte civile, \u00e0 un litige potentiel ou r\u00e9el, ou \u00e0 d&#039;autres proc\u00e9dures judiciaires contradictoires, et pour faire respecter ou enqu\u00eater sur les violations potentielles de nos conditions ou politiques.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment nous divulguons les renseignements personnels<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Dans certaines circonstances, nous pouvons divulguer vos renseignements personnels \u00e0 des tiers \u00e0 des fins l\u00e9gitimes, conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9. Ces circonstances peuvent inclure\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avec les fournisseurs et autres tiers qui effectuent des services en notre nom (par exemple, la gestion informatique, le traitement des paiements, l&#039;analyse des donn\u00e9es, le support client, le stockage cloud, l&#039;ex\u00e9cution et l&#039;exp\u00e9dition).<\/li>\n\n\n\n<li>Avec des partenaires commerciaux et marketing pour vous fournir des services de marketing et faire de la publicit\u00e9.<\/li>\n\n\n\n<li>Lorsque vous nous le demandez, nous le demandez ou consentez autrement \u00e0 ce que nous divulguions certaines informations \u00e0 des tiers, par exemple pour vous exp\u00e9dier des produits ou par le biais de votre utilisation de widgets de m\u00e9dias sociaux ou d&#039;int\u00e9grations de connexion.<\/li>\n\n\n\n<li>Avec nos filiales ou au sein de notre groupe.<\/li>\n\n\n\n<li>Dans le cadre d&#039;une transaction commerciale telle qu&#039;une fusion ou une faillite, pour se conformer \u00e0 toutes les obligations l\u00e9gales applicables (y compris pour r\u00e9pondre aux assignations, aux mandats de perquisition et aux demandes similaires), pour faire respecter toutes les conditions d&#039;utilisation ou politiques applicables, et pour prot\u00e9ger ou d\u00e9fendre les Services, nos droits et les droits de nos utilisateurs ou d&#039;autres personnes.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sites Web et liens tiers<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Les Services peuvent contenir des liens vers des sites web ou autres plateformes en ligne exploit\u00e9s par des tiers. Si vous suivez des liens vers des sites qui ne sont ni affili\u00e9s ni contr\u00f4l\u00e9s par nous, nous vous recommandons de consulter leurs politiques de confidentialit\u00e9 et de s\u00e9curit\u00e9 ainsi que leurs autres conditions d&#039;utilisation. Nous ne garantissons ni la confidentialit\u00e9 ni la s\u00e9curit\u00e9 de ces sites, et nous d\u00e9clinons toute responsabilit\u00e9 \u00e0 cet \u00e9gard, notamment quant \u00e0 l&#039;exactitude, l&#039;exhaustivit\u00e9 ou la fiabilit\u00e9 des informations qui y figurent. Les informations que vous publiez sur des plateformes publiques ou semi-publiques, y compris celles que vous partagez sur les r\u00e9seaux sociaux, peuvent \u00eatre consult\u00e9es par d&#039;autres utilisateurs des Services et\/ou de ces plateformes, sans restriction quant \u00e0 leur utilisation par nous ou par un tiers. L&#039;inclusion de ces liens n&#039;implique en aucun cas une approbation du contenu de ces plateformes, ni de leurs propri\u00e9taires ou exploitants, sauf mention contraire dans les Services.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Donn\u00e9es sur les enfants<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Nos services ne sont pas destin\u00e9s aux enfants et nous ne recueillons sciemment aucune information personnelle concernant les mineurs dans votre juridiction. Si vous \u00eates le parent ou le tuteur d&#039;un enfant qui nous a communiqu\u00e9 ses informations personnelles, vous pouvez nous contacter aux coordonn\u00e9es ci-dessous pour demander leur suppression. \u00c0 la date d&#039;entr\u00e9e en vigueur de la pr\u00e9sente politique de confidentialit\u00e9, nous n&#039;avons pas connaissance de \u201c\u00a0partager\u00a0\u201d ou de \u201c\u00a0vendre\u00a0\u201d (au sens de la loi applicable) les informations personnelles de personnes de moins de 16\u00a0ans.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>S\u00e9curit\u00e9 et conservation de vos informations<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Veuillez noter qu&#039;aucune mesure de s\u00e9curit\u00e9 n&#039;est infaillible et que nous ne pouvons garantir une s\u00e9curit\u00e9 absolue. De plus, les informations que vous nous transmettez peuvent ne pas \u00eatre s\u00e9curis\u00e9es pendant leur transmission. Nous vous recommandons de ne pas utiliser de canaux non s\u00e9curis\u00e9s pour nous communiquer des informations sensibles ou confidentielles.<\/p>\n\n\n\n<p>La dur\u00e9e pendant laquelle nous conservons vos informations personnelles d\u00e9pend de diff\u00e9rents facteurs, notamment si nous avons besoin de ces informations pour g\u00e9rer votre compte, vous fournir des services, respecter nos obligations l\u00e9gales, r\u00e9soudre des litiges ou faire appliquer d&#039;autres contrats et politiques applicables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vos droits et vos choix<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Selon votre lieu de r\u00e9sidence, vous pouvez b\u00e9n\u00e9ficier de certains ou de l&#039;ensemble des droits \u00e9num\u00e9r\u00e9s ci-dessous concernant vos donn\u00e9es personnelles. Toutefois, ces droits ne sont pas absolus, peuvent ne s&#039;appliquer que dans certaines circonstances et, dans certains cas, nous pouvons refuser votre demande conform\u00e9ment \u00e0 la loi.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Droit d&#039;acc\u00e8s \/ de connaissance.<\/strong>&nbsp;Vous pouvez avoir le droit de demander l&#039;acc\u00e8s aux renseignements personnels que nous d\u00e9tenons \u00e0 votre sujet.<\/li>\n\n\n\n<li><strong>Droit \u00e0 l&#039;effacement.<\/strong>&nbsp;Vous pouvez avoir le droit de demander la suppression des informations personnelles que nous conservons vous concernant.<\/li>\n\n\n\n<li><strong>Droit de rectification.<\/strong>&nbsp;Vous pouvez avoir le droit de demander que nous corrigions les renseignements personnels inexacts que nous d\u00e9tenons \u00e0 votre sujet.<\/li>\n\n\n\n<li><strong>Droit \u00e0 la portabilit\u00e9.<\/strong>&nbsp;Vous pouvez avoir le droit de recevoir une copie des renseignements personnels que nous d\u00e9tenons \u00e0 votre sujet et de demander que nous les transf\u00e9rions \u00e0 un tiers, dans certaines circonstances et sous r\u00e9serve de certaines exceptions.<\/li>\n\n\n\n<li><strong>Droit de refuser la vente ou le partage de vos donn\u00e9es \u00e0 des fins de publicit\u00e9 cibl\u00e9e.<\/strong>&nbsp;Selon votre lieu de r\u00e9sidence, vous pouvez avoir le droit de vous opposer \u00e0 la \u201c vente \u201d ou au \u201c partage \u201d de vos renseignements personnels ou de vous opposer au traitement de vos renseignements personnels \u00e0 des fins consid\u00e9r\u00e9es comme de la \u201c publicit\u00e9 cibl\u00e9e \u201d, telles que d\u00e9finies dans les lois applicables en mati\u00e8re de protection de la vie priv\u00e9e.<\/li>\n\n\n\n<li><strong>Gestion des pr\u00e9f\u00e9rences de communication.<\/strong>&nbsp;Nous pouvons vous envoyer des courriels promotionnels, et vous pouvez vous d\u00e9sabonner \u00e0 tout moment en utilisant le lien de d\u00e9sabonnement figurant dans nos courriels. M\u00eame si vous vous d\u00e9sabonnez, nous pourrons toujours vous envoyer des courriels non promotionnels, comme ceux concernant votre compte ou vos commandes.<\/li>\n<\/ul>\n\n\n\n<p><strong>Si vous r\u00e9sidez au Royaume-Uni ou dans l&#039;Espace \u00e9conomique europ\u00e9en,<\/strong>&nbsp;et sous r\u00e9serve des exceptions et limitations pr\u00e9vues par la l\u00e9gislation locale, vous pouvez exercer les droits suivants en plus des droits \u00e9nonc\u00e9s ci-dessus\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Opposition au traitement et limitation du traitement\u00a0:<\/strong>&nbsp;Vous pouvez avoir le droit de nous demander de cesser ou de limiter le traitement de vos donn\u00e9es personnelles \u00e0 certaines fins.<\/li>\n\n\n\n<li><strong>Retrait du consentement :<\/strong>&nbsp;Lorsque nous traitons vos donn\u00e9es personnelles sur la base de votre consentement, vous avez le droit de le retirer. Ce retrait n&#039;affectera pas la lic\u00e9it\u00e9 des traitements effectu\u00e9s avant ce retrait.<\/li>\n<\/ul>\n\n\n\n<p>Vous pouvez exercer l&#039;un quelconque de ces droits aux endroits indiqu\u00e9s dans les Services ou en nous contactant en utilisant les coordonn\u00e9es fournies ci-dessous.<\/p>\n\n\n\n<p>Nous ne vous discriminerons pas si vous exercez l&#039;un de ces droits. Nous pourrions avoir besoin de v\u00e9rifier votre identit\u00e9 avant de traiter vos demandes, conform\u00e9ment \u00e0 la loi applicable. Conform\u00e9ment \u00e0 la loi, vous pouvez d\u00e9signer un mandataire pour effectuer des demandes en votre nom afin d&#039;exercer vos droits. Avant d&#039;accepter une telle demande, nous exigerons de votre mandataire qu&#039;il fournisse la preuve de votre mandat et nous pourrions vous demander de v\u00e9rifier votre identit\u00e9 directement aupr\u00e8s de nous. Nous r\u00e9pondrons \u00e0 votre demande dans les meilleurs d\u00e9lais, conform\u00e9ment \u00e0 la loi applicable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Plaintes<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Si vous avez des r\u00e9clamations concernant le traitement de vos donn\u00e9es personnelles, veuillez nous contacter aux coordonn\u00e9es ci-dessous. Selon votre lieu de r\u00e9sidence, vous pouvez avoir le droit de faire appel de notre d\u00e9cision en nous contactant aux coordonn\u00e9es ci-dessous ou de d\u00e9poser une plainte aupr\u00e8s de votre autorit\u00e9 de protection des donn\u00e9es locale. Pour l&#039;EEE, vous trouverez la liste des autorit\u00e9s de contr\u00f4le comp\u00e9tentes en mati\u00e8re de protection des donn\u00e9es. <a href=\"https:\/\/edpb.europa.eu\/about-edpb\/about-edpb\/members\" target=\"_blank\" rel=\"noopener\"><u>ici<\/u><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Transferts internationaux<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Veuillez noter que nous pouvons transf\u00e9rer, stocker et traiter vos informations personnelles en dehors du pays o\u00f9 vous r\u00e9sidez.<\/p>\n\n\n\n<p>Si nous transf\u00e9rons vos informations personnelles hors de l&#039;Espace \u00e9conomique europ\u00e9en ou du Royaume-Uni, nous nous appuierons sur des m\u00e9canismes de transfert reconnus tels que les clauses contractuelles types de la Commission europ\u00e9enne, ou tout contrat \u00e9quivalent \u00e9mis par l&#039;autorit\u00e9 comp\u00e9tente du Royaume-Uni, le cas \u00e9ch\u00e9ant, sauf si le transfert de donn\u00e9es est effectu\u00e9 vers un pays qui a \u00e9t\u00e9 jug\u00e9 comme assurant un niveau de protection ad\u00e9quat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Modifications apport\u00e9es \u00e0 la pr\u00e9sente politique de confidentialit\u00e9<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Nous pouvons \u00eatre amen\u00e9s \u00e0 modifier la pr\u00e9sente Politique de confidentialit\u00e9, notamment pour tenir compte de l&#039;\u00e9volution de nos pratiques ou pour d&#039;autres raisons op\u00e9rationnelles, juridiques ou r\u00e9glementaires. La version r\u00e9vis\u00e9e sera publi\u00e9e sur ce site web, la date de \u201c\u00a0Derni\u00e8re mise \u00e0 jour\u00a0\u201d sera actualis\u00e9e et nous vous en informerons conform\u00e9ment \u00e0 la l\u00e9gislation applicable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Contact<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Si vous avez des questions concernant nos pratiques en mati\u00e8re de confidentialit\u00e9 ou la pr\u00e9sente politique de confidentialit\u00e9, ou si vous souhaitez exercer l&#039;un de vos droits, veuillez nous appeler ou nous envoyer un courriel \u00e0 Info@MountLaser.COM ou nous contacter \u00e0 l&#039;adresse suivante\u00a0: Lijia Town, Wujin District, Changzhou, 213165, CN. Aux fins des lois applicables en mati\u00e8re de protection des donn\u00e9es, nous sommes le responsable du traitement de vos donn\u00e9es personnelles.<\/p>\n\n\n\n<p>Derni\u00e8re mise \u00e0 jour : 23 septembre 2025<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Mount Laser operates this store and website, including all related information, content, features, tools, products and services, in order to provide you, the customer, with a curated shopping experience (the &#8220;Services&#8221;). This Privacy Policy describes how we collect, use, and disclose your personal information when you visit, use, or make a purchase or [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1596","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/pages\/1596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=1596"}],"version-history":[{"count":1,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/pages\/1596\/revisions"}],"predecessor-version":[{"id":2048,"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/pages\/1596\/revisions\/2048"}],"wp:attachment":[{"href":"https:\/\/mountlaser.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=1596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}