{"id":143,"count":3,"description":"El bloqueo de rosca para jal\u00f3n GPS es un mecanismo de bloqueo de precisi\u00f3n dise\u00f1ado para asegurar las conexiones roscadas en jalones topogr\u00e1ficos y varillas GNSS, garantizando la m\u00e1xima estabilidad durante las mediciones de campo. Dise\u00f1ado para evitar el aflojamiento causado por vibraciones, cambios de temperatura o movimientos repetitivos, este bloqueo de rosca proporciona una sujeci\u00f3n firme y fiable entre las secciones del jal\u00f3n, los adaptadores y los instrumentos topogr\u00e1ficos montados. Fabricado con materiales de alta resistencia y resistentes al desgaste, el bloqueo de rosca para jal\u00f3n GPS mantiene un rendimiento de bloqueo a largo plazo incluso en entornos exteriores exigentes. Su suave acci\u00f3n de bloqueo permite a los top\u00f3grafos apretar y soltar componentes r\u00e1pidamente sin comprometer la precisi\u00f3n. Tanto si se utiliza en un jal\u00f3n GPS est\u00e1ndar como en una varilla GNSS de alta precisi\u00f3n, ayuda a mantener la altura del equipo constante y elimina movimientos de rotaci\u00f3n no deseados durante las tareas topogr\u00e1ficas.","link":"https:\/\/mountlaser.com\/es\/categoria-producto\/surveying-pole-rod\/gps-pole-thread-lock\/","name":"Bloqueo de rosca para poste de GPS","slug":"gps-pole-thread-lock","taxonomy":"product_cat","parent":89,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/89"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product?product_cat=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}