{"id":131,"count":0,"description":"El adaptador de nivel l\u00e1ser es un accesorio de montaje vers\u00e1til y esencial, dise\u00f1ado para mejorar la compatibilidad y la estabilidad al utilizar diferentes tipos de niveles l\u00e1ser. Dise\u00f1ado para trabajos profesionales de construcci\u00f3n, topograf\u00eda e instalaci\u00f3n en interiores, este adaptador proporciona una conexi\u00f3n segura entre su herramienta l\u00e1ser y tr\u00edpodes, soportes o plataformas elevadoras. Fabricado con materiales duraderos y roscado de precisi\u00f3n, el adaptador de nivel l\u00e1ser garantiza una instalaci\u00f3n sencilla y un soporte fiable durante las tareas de nivelaci\u00f3n, alineaci\u00f3n y replanteo. Ya sea que necesite cambiar el tama\u00f1o de la rosca o lograr una mayor flexibilidad de montaje, este adaptador ofrece un rendimiento uniforme en una amplia gama de aplicaciones en la obra.","link":"https:\/\/mountlaser.com\/es\/categoria-producto\/laser-level-accessory\/laser-level-adapter\/","name":"Adaptador de nivel l\u00e1ser","slug":"laser-level-adapter","taxonomy":"product_cat","parent":94,"meta":[],"menu_order":54,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/94"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product?product_cat=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}