{"id":124,"count":6,"description":"El Jal\u00f3n Prisma de Aluminio y Fibra de Vidrio representa una fusi\u00f3n superior de dos materiales de alto rendimiento, dise\u00f1ados para brindar una experiencia de campo excepcional. Al combinar la ligereza y la resistencia a la corrosi\u00f3n del aluminio con la excepcional resistencia y seguridad no conductora de la fibra de vidrio, este jal\u00f3n ofrece lo mejor de ambos mundos. El Jal\u00f3n Prisma de Aluminio y Fibra de Vidrio est\u00e1 dise\u00f1ado para mantenerse estable y recto en condiciones exigentes, proporcionando a los top\u00f3grafos una extensi\u00f3n fiable para su prisma o GPS m\u00f3vil.","link":"https:\/\/mountlaser.com\/es\/categoria-producto\/surveying-pole-rod\/aluminum-fiberglass-prism-pole\/","name":"Poste de prisma de aluminio y fibra de vidrio","slug":"aluminum-fiberglass-prism-pole","taxonomy":"product_cat","parent":89,"meta":[],"menu_order":30,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/89"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product?product_cat=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}