{"id":114,"count":12,"description":"El Mini Prisma con Jal\u00f3n es una soluci\u00f3n topogr\u00e1fica compacta y vers\u00e1til, dise\u00f1ada para la medici\u00f3n de distancias y el monitoreo de deformaciones con alta precisi\u00f3n. Dise\u00f1ado para brindar precisi\u00f3n y portabilidad, integra un mini prisma de alta calidad con un jal\u00f3n ligero y extensible para una f\u00e1cil instalaci\u00f3n en campo. Con una carcasa de aluminio anodizado duradero y materiales resistentes a la corrosi\u00f3n, el Mini Prisma con Jal\u00f3n garantiza resultados estables y repetibles incluso en entornos exteriores hostiles. Compatible con prismas recubiertos de cobre y plata, proporciona una excelente reflectividad y consistencia en las mediciones. Ideal para dise\u00f1o de obras, estudios de ingenier\u00eda y monitoreo geot\u00e9cnico, el Mini Prisma con Jal\u00f3n ofrece flexibilidad, precisi\u00f3n y confiabilidad en un solo paquete de calidad profesional.","link":"https:\/\/mountlaser.com\/es\/categoria-producto\/reflective-target-prism\/mini-prism-with-pole\/","name":"Mini prisma con poste","slug":"mini-prism-with-pole","taxonomy":"product_cat","parent":72,"meta":[],"menu_order":10,"_links":{"self":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product_cat\/72"}],"wp:post_type":[{"href":"https:\/\/mountlaser.com\/es\/wp-json\/wp\/v2\/product?product_cat=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}